{"id":121,"count":1,"description":"","link":"https:\/\/vclubgurgaon.com\/blog\/tag\/wedding-lawn-in-gurgaon\/","name":"wedding lawn in Gurgaon","slug":"wedding-lawn-in-gurgaon","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/vclubgurgaon.com\/blog\/wp-json\/wp\/v2\/tags\/121"}],"collection":[{"href":"https:\/\/vclubgurgaon.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/vclubgurgaon.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/vclubgurgaon.com\/blog\/wp-json\/wp\/v2\/posts?tags=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}